{"id":710,"date":"2025-06-18T09:38:05","date_gmt":"2025-06-18T09:38:05","guid":{"rendered":"https:\/\/haberling.northitgroup.eu\/?page_id=710"},"modified":"2026-05-26T17:21:24","modified_gmt":"2026-05-26T14:21:24","slug":"high-tech-transport","status":"publish","type":"page","link":"https:\/\/www.haberling.de\/en\/high-tech-transport\/","title":{"rendered":"High-tech transport"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"article-content.php","meta":{"_acf_changed":false,"footnotes":""},"services":[8],"class_list":["post-710","page","type-page","status-publish","hentry","services-spezialtransporte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>High-Tech-Transport - Haberling<\/title>\n<meta name=\"description\" content=\"High-Tech-Transport bei der Haberling GmbH: Planung und Durchf\u00fchrung sensibler Transporte f\u00fcr technische Anlagen, IT-Systeme und spezialisierte Infrastruktur.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.haberling.de\/en\/high-tech-transport\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"High-Tech-Transport - Haberling\" \/>\n<meta property=\"og:description\" content=\"High-Tech-Transport bei der Haberling GmbH: Planung und Durchf\u00fchrung sensibler Transporte f\u00fcr technische Anlagen, IT-Systeme und spezialisierte Infrastruktur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.haberling.de\/en\/high-tech-transport\/\" \/>\n<meta property=\"og:site_name\" content=\"Haberling\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T14:21:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.haberling.de\\\/high-tech-transport\\\/\",\"url\":\"https:\\\/\\\/www.haberling.de\\\/high-tech-transport\\\/\",\"name\":\"High-Tech-Transport - Haberling\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.haberling.de\\\/#website\"},\"datePublished\":\"2025-06-18T09:38:05+00:00\",\"dateModified\":\"2026-05-26T14:21:24+00:00\",\"description\":\"High-Tech-Transport bei der Haberling GmbH: Planung und Durchf\u00fchrung sensibler Transporte f\u00fcr technische Anlagen, IT-Systeme und spezialisierte Infrastruktur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.haberling.de\\\/high-tech-transport\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.haberling.de\\\/high-tech-transport\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.haberling.de\\\/high-tech-transport\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.haberling.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"High-Tech-Transport\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.haberling.de\\\/#website\",\"url\":\"https:\\\/\\\/www.haberling.de\\\/\",\"name\":\"Template\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.haberling.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.haberling.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.haberling.de\\\/#organization\",\"name\":\"Template\",\"url\":\"https:\\\/\\\/www.haberling.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.haberling.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.haberling.de\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo.png.svg\",\"contentUrl\":\"https:\\\/\\\/www.haberling.de\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo.png.svg\",\"width\":129,\"height\":42,\"caption\":\"Template\"},\"image\":{\"@id\":\"https:\\\/\\\/www.haberling.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"High-Tech-Transport - Haberling","description":"High-Tech-Transport bei der Haberling GmbH: Planung und Durchf\u00fchrung sensibler Transporte f\u00fcr technische Anlagen, IT-Systeme und spezialisierte Infrastruktur.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.haberling.de\/en\/high-tech-transport\/","og_locale":"en_GB","og_type":"article","og_title":"High-Tech-Transport - Haberling","og_description":"High-Tech-Transport bei der Haberling GmbH: Planung und Durchf\u00fchrung sensibler Transporte f\u00fcr technische Anlagen, IT-Systeme und spezialisierte Infrastruktur.","og_url":"https:\/\/www.haberling.de\/en\/high-tech-transport\/","og_site_name":"Haberling","article_modified_time":"2026-05-26T14:21:24+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.haberling.de\/high-tech-transport\/","url":"https:\/\/www.haberling.de\/high-tech-transport\/","name":"High-Tech-Transport - Haberling","isPartOf":{"@id":"https:\/\/www.haberling.de\/#website"},"datePublished":"2025-06-18T09:38:05+00:00","dateModified":"2026-05-26T14:21:24+00:00","description":"High-Tech-Transport bei der Haberling GmbH: Planung und Durchf\u00fchrung sensibler Transporte f\u00fcr technische Anlagen, IT-Systeme und spezialisierte Infrastruktur.","breadcrumb":{"@id":"https:\/\/www.haberling.de\/high-tech-transport\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.haberling.de\/high-tech-transport\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.haberling.de\/high-tech-transport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.haberling.de\/"},{"@type":"ListItem","position":2,"name":"High-Tech-Transport"}]},{"@type":"WebSite","@id":"https:\/\/www.haberling.de\/#website","url":"https:\/\/www.haberling.de\/","name":"Template","description":"","publisher":{"@id":"https:\/\/www.haberling.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.haberling.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.haberling.de\/#organization","name":"Template","url":"https:\/\/www.haberling.de\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.haberling.de\/#\/schema\/logo\/image\/","url":"https:\/\/www.haberling.de\/wp-content\/uploads\/2025\/05\/logo.png.svg","contentUrl":"https:\/\/www.haberling.de\/wp-content\/uploads\/2025\/05\/logo.png.svg","width":129,"height":42,"caption":"Template"},"image":{"@id":"https:\/\/www.haberling.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.haberling.de\/en\/wp-json\/wp\/v2\/pages\/710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.haberling.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.haberling.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.haberling.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.haberling.de\/en\/wp-json\/wp\/v2\/comments?post=710"}],"version-history":[{"count":0,"href":"https:\/\/www.haberling.de\/en\/wp-json\/wp\/v2\/pages\/710\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.haberling.de\/en\/wp-json\/wp\/v2\/media?parent=710"}],"wp:term":[{"taxonomy":"services","embeddable":true,"href":"https:\/\/www.haberling.de\/en\/wp-json\/wp\/v2\/services?post=710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}